{"id":1100,"date":"2025-05-06T00:15:04","date_gmt":"2025-05-06T00:15:04","guid":{"rendered":"http:\/\/beautifulsod.local\/?page_id=1100"},"modified":"2026-07-07T08:41:14","modified_gmt":"2026-07-07T14:41:14","slug":"install","status":"publish","type":"page","link":"https:\/\/mcsod.com\/es\/resources\/how-to\/install\/","title":{"rendered":"Gu\u00eda De Instalaci\u00f3n"},"content":{"rendered":"<div class=\"wp-block-stackable-columns stk-block-columns stk-block stk-aebffb4\" data-block-id=\"aebffb4\"><style>.stk-aebffb4-column{--stk-columns-spacing:0px !important;}<\/style><div class=\"stk-row stk-inner-blocks stk-block-content stk-content-align stk-aebffb4-column\">\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-0f99ccd\" data-v=\"4\" data-block-id=\"0f99ccd\"><style>@media screen and (min-width:690px){.stk-0f99ccd {flex:var(--stk-flex-grow, 1) 1 calc(80% - var(--stk-column-gap, 0px) * 2 \/ 3 ) !important;}}@media screen and (min-width:690px) and (max-width:999px){.stk-0f99ccd {flex:var(--stk-flex-grow, 1) 1 calc(60% - var(--stk-column-gap, 0px) * 2 \/ 3 ) !important;}}@media screen and (max-width:689px){.stk-0f99ccd {flex:var(--stk-flex-grow, 1) 1 calc(100% - var(--stk-column-gap, 0px) * 0 \/ 1 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-0f99ccd-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-0f99ccd-inner-blocks\">\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-abe2076\" id=\"measuring-your-yard\" data-block-id=\"abe2076\"><h2 class=\"stk-block-heading__text\">MEDICI\u00d3N DE SU PATIO<\/h2><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-e40b816\" data-v=\"4\" data-block-id=\"e40b816\"><style>@media screen and (min-width:690px){.stk-e40b816 {flex:var(--stk-flex-grow, 1) 1 calc(10% - var(--stk-column-gap, 0px) * 2 \/ 3 ) !important;}}@media screen and (min-width:690px) and (max-width:999px){.stk-e40b816 {flex:var(--stk-flex-grow, 1) 1 calc(20% - var(--stk-column-gap, 0px) * 2 \/ 3 ) !important;}}@media screen and (max-width:689px){.stk-e40b816 {flex:var(--stk-flex-grow, 1) 1 calc(50% - var(--stk-column-gap, 0px) * 1 \/ 2 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-e40b816-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-e40b816-inner-blocks\">\n<div class=\"wp-block-file\"><a href=\"https:\/\/mcsod.com\/wp-content\/uploads\/2026\/07\/laying-kentucky-bluegrass-2026.pdf\" class=\"wp-block-file__button wp-element-button\" download>Download<\/a><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-column stk-block-column stk-column stk-block stk-a1fdc2e\" data-v=\"4\" data-block-id=\"a1fdc2e\"><style>@media screen and (min-width:690px){.stk-a1fdc2e {flex:var(--stk-flex-grow, 1) 1 calc(10% - var(--stk-column-gap, 0px) * 2 \/ 3 ) !important;}}@media screen and (min-width:690px) and (max-width:999px){.stk-a1fdc2e {flex:var(--stk-flex-grow, 1) 1 calc(20% - var(--stk-column-gap, 0px) * 2 \/ 3 ) !important;}}@media screen and (max-width:689px){.stk-a1fdc2e {flex:var(--stk-flex-grow, 1) 1 calc(50% - var(--stk-column-gap, 0px) * 1 \/ 2 ) !important;}}<\/style><div class=\"stk-column-wrapper stk-block-column__content stk-container stk-a1fdc2e-container stk--no-background stk--no-padding\"><div class=\"stk-block-content stk-inner-blocks stk-a1fdc2e-inner-blocks\">\n<div class=\"wp-block-file\"><a href=\"https:\/\/mcsod.com\/wp-content\/uploads\/2026\/07\/spanish-of-laying-kentucky-bluegrass-2026.pdf\" class=\"wp-block-file__button wp-element-button\" download>Descargar<\/a><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-5c321e6\" data-block-id=\"5c321e6\"><p class=\"stk-block-text__text\">La manera m\u00e1s f\u00e1cil de empezar a medir es dividir el jard\u00edn en formas b\u00e1sicas; los rect\u00e1ngulos o cuadrados son los m\u00e1s f\u00e1ciles. Luego, puedes calcular el \u00e1rea de cada forma y sumarlas para obtener el total de metros cuadrados de tu jard\u00edn. Te sugerimos a\u00f1adir un 5 % adicional a la medida por si acaso.<\/p><\/div>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-4b9126b\" id=\"preparing-your-ground\" data-block-id=\"4b9126b\"><h2 class=\"stk-block-heading__text\">PREPARANDO EL TERRENO<\/h2><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-40bf086\" data-block-id=\"40bf086\"><p class=\"stk-block-text__text\">Para garantizar un c\u00e9sped verde y saludable, es importante preparar el terreno antes de colocar el c\u00e9sped.<\/p><\/div>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Retire todas las rocas, escombros, materia org\u00e1nica y malezas vivas o muertas. Desenterre el sistema radicular de las malezas siempre que sea posible.<\/li>\n\n\n\n<li>Revisa tu tipo de suelo para determinar qu\u00e9 nutrientes necesita, si los necesita. Desentierra un par de paladas y ll\u00e9valo a un vivero local o pregunta a tus vecinos si lo saben.<\/li>\n\n\n\n<li>Dadas las temperaturas de Treasure Valley, es casi imprescindible instalar un sistema de riego, ya sea por aspersi\u00f3n o por inundaci\u00f3n. Mantener un c\u00e9sped verde y saludable reg\u00e1ndolo manualmente puede ser bastante dif\u00edcil.<\/li>\n\n\n\n<li>Nivele y alise el suelo. Aseg\u00farese de que no haya zonas deprimidas donde se acumule agua. Nivele a una pulgada por debajo de bordillos, aceras, entradas de veh\u00edculos, etc.<\/li>\n\n\n\n<li>Si bien no es necesario pero s\u00ed beneficioso, puedes mejorar las condiciones del suelo agregando una capa ligera de abono y\/o un fertilizante inicial en toda el \u00e1rea de plantaci\u00f3n.<\/li>\n\n\n\n<li>Con un par de pasadas con un rastrillo de jardiner\u00eda, combine el abono, el fertilizante y la tierra.<\/li>\n<\/ol>\n\n\n\n<div class=\"wp-block-stackable-heading stk-block-heading stk-block-heading--v2 stk-block stk-d96f6c9\" id=\"laying-your-sod\" data-block-id=\"d96f6c9\"><h2 class=\"stk-block-heading__text\">COLOCANDO SU C\u00c9SPED<\/h2><\/div>\n\n\n\n<div class=\"wp-block-stackable-text stk-block-text stk-block stk-d203263\" data-block-id=\"d203263\"><p class=\"stk-block-text__text\">Estos pasos le ayudar\u00e1n a guiarse a trav\u00e9s del proceso de instalaci\u00f3n de su nuevo c\u00e9sped Kentucky Bluegrass. C\u00e9sped <span style=\"text-decoration: underline;\"><strong>DEBE<\/strong><\/span> se instalar\u00e1\/colocar\u00e1 el <span style=\"text-decoration: underline;\"><strong>MISMO D\u00cdA<\/strong><\/span> se entrega o se recoge. Si se deja enrollado en el pal\u00e9, empezar\u00e1 a amarillear y su calidad se deteriorar\u00e1.<\/p><\/div>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Siempre que sea posible, solicite que le entreguen el c\u00e9sped en la zona donde se instalar\u00e1. Cada rollo pesa entre 30 y 40 libras. <strong>Nuestra carretilla elevadora necesita 9 pies de espacio libre de lado a lado para poder acceder.&nbsp;<\/strong><\/li>\n\n\n\n<li>Para empezar, coloque rollos de c\u00e9sped a lo largo del borde m\u00e1s largo de su jard\u00edn. Luego, haga lo mismo en el borde perpendicular.<\/li>\n\n\n\n<li>De los rollos de borde que ya coloc\u00f3, escalone el c\u00e9sped como si estuviera colocando ladrillos paralelos al borde m\u00e1s largo del jard\u00edn. Coloque un rollo completo y luego corte un segundo rollo por la mitad de 2.5 pies de largo de largo y col\u00f3quelo junto al rollo completo. Use un rollo completo para el tercero. Luego contin\u00fae con la segunda mitad del rollo cortado. Contin\u00fae por todo el jard\u00edn.<\/li>\n\n\n\n<li>Use un cuchillo afilado para recortar el c\u00e9sped a lo largo de las curvas y hacer agujeros para los aspersores. Cortar a trav\u00e9s de la tierra\/ra\u00edz del c\u00e9sped (el lado con tierra, no las briznas de hierba) suele ser m\u00e1s efectivo y proporciona cortes m\u00e1s limpios.<\/li>\n\n\n\n<li>A\u00f1ade tierra en los puntos bajos y retira tierra de los puntos altos.<\/li>\n\n\n\n<li>Una vez colocado el c\u00e9sped, ri\u00e9guelo bien, asegur\u00e1ndose de que el agua se sature a trav\u00e9s del c\u00e9sped hasta el suelo que se encuentra debajo, al menos dos pulgadas por debajo del c\u00e9sped.<\/li>\n\n\n\n<li>Para el cuidado continuo de su patio nuevo o existente, visite nuestro <a href=\"https:\/\/mcsod.com\/es\/resources\/how-to\/care\/\" data-type=\"page\" data-id=\"1098\">p\u00e1gina de cuidados<\/a>.<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>MEASURING YOUR YARD The easiest way to begin measuring is to break your yard up into basic shapes \u2014 rectangles or squares are the easiest. You can then find the area of each shape and add them together for the total square footage of your yard. We suggest adding about 5 percent extra to your [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":2197,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Sod Installation Guide - Prepare and Lay Sod - McKellip Sod","_seopress_titles_desc":"From ground prep to first watering, our installation guide helps ensure a successful sod project. Start with confidence and get lasting results.","_seopress_robots_index":"","footnotes":""},"class_list":["post-1100","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/mcsod.com\/es\/wp-json\/wp\/v2\/pages\/1100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcsod.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcsod.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcsod.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mcsod.com\/es\/wp-json\/wp\/v2\/comments?post=1100"}],"version-history":[{"count":2,"href":"https:\/\/mcsod.com\/es\/wp-json\/wp\/v2\/pages\/1100\/revisions"}],"predecessor-version":[{"id":2344,"href":"https:\/\/mcsod.com\/es\/wp-json\/wp\/v2\/pages\/1100\/revisions\/2344"}],"up":[{"embeddable":true,"href":"https:\/\/mcsod.com\/es\/wp-json\/wp\/v2\/pages\/2197"}],"wp:attachment":[{"href":"https:\/\/mcsod.com\/es\/wp-json\/wp\/v2\/media?parent=1100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}